{"id":231,"date":"2010-02-19T10:06:34","date_gmt":"2010-02-19T09:06:34","guid":{"rendered":"https:\/\/www.inmsol.com\/"},"modified":"2019-05-02T12:06:23","modified_gmt":"2019-05-02T10:06:23","slug":"fechas-de-examenes-dele-2013","status":"publish","type":"post","link":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/","title":{"rendered":"Fechas de ex\u00e1menes D.E.L.E. 2013"},"content":{"rendered":"<p class=\"rtecenter\"><strong>FECHAS DE EX\u00c1MENES DELE 2013<\/strong><\/p>\n<p><strong>Mayo de 2013<\/strong><\/p>\n<ul>\n<li><strong>Fechas de examen<\/strong>: D\u00edas 24 y 25 de mayo, seg\u00fan pa\u00edses.<\/li>\n<li><strong>Plazo de inscripci\u00f3n<\/strong>: desde el 25 de febrero hasta el 19 de abril, ambos inclusive.<\/li>\n<\/ul>\n<p>\n<strong>Agosto de 2013<\/strong><\/p>\n<ul>\n<li><strong>Fecha de examen<\/strong>: D\u00eda 23 de agosto, seg\u00fan pa\u00edses.<\/li>\n<li><strong>Plazo de inscripci\u00f3n<\/strong>: desde el 1 de julio hasta el 26 de julio, ambos inclusive.\u00a0<\/li>\n<\/ul>\n<p>\n<strong>Noviembre de 2013<\/strong><\/p>\n<ul>\n<li><strong>Fechas de examen<\/strong>: D\u00edas 22 y 23 de noviembre, seg\u00fan pa\u00edses.<\/li>\n<li><strong>Plazo de inscripci\u00f3n<\/strong>: desde el 16 de septiembre hasta el 18 de octubre, ambos inclusive.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>FECHAS DE EX\u00c1MENES DELE 2013 Mayo de 2013 Fechas de examen: D\u00edas 24 y 25 de mayo, seg\u00fan pa\u00edses. Plazo de inscripci\u00f3n: desde el 25 de febrero hasta el 19 de abril, ambos inclusive. Agosto de 2013 Fecha de examen: D\u00eda 23 de agosto, seg\u00fan&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[451],"tags":[],"class_list":["post-231","post","type-post","status-publish","format-standard","hentry","category-examenes-y-certificaciones-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocatoria D.E.L.E. 2013 | INMSOL<\/title>\n<meta name=\"description\" content=\"FECHAS DE EX\u00c1MENES DELE 2013\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocatoria D.E.L.E. 2013 | INMSOL\" \/>\n<meta property=\"og:description\" content=\"FECHAS DE EX\u00c1MENES DELE 2013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"iNMSOL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/spanishcourses\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-19T09:06:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-02T10:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inmsol.com\/wp-content\/uploads\/2019\/08\/logo-inmsol.png\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Javier Torres\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Torres\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/\"},\"author\":{\"name\":\"Javier Torres\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#\\\/schema\\\/person\\\/18f18acd0397ef441e373e79ec3eb6ea\"},\"headline\":\"Fechas de ex\u00e1menes D.E.L.E. 2013\",\"datePublished\":\"2010-02-19T09:06:34+00:00\",\"dateModified\":\"2019-05-02T10:06:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#organization\"},\"articleSection\":[\"Ex\u00e1menes y Certificaciones Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/\",\"url\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/\",\"name\":\"Convocatoria D.E.L.E. 2013 | INMSOL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#website\"},\"datePublished\":\"2010-02-19T09:06:34+00:00\",\"dateModified\":\"2019-05-02T10:06:23+00:00\",\"description\":\"FECHAS DE EX\u00c1MENES DELE 2013\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/examenes-y-certificaciones-espanol\\\/fechas-de-examenes-dele-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accredited Center by Instituto Cervantes\",\"item\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/pagina-ejemplo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex\u00e1menes y Certificaciones Espa\u00f1ol\",\"item\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/category\\\/examenes-y-certificaciones-espanol\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fechas de ex\u00e1menes D.E.L.E. 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/\",\"name\":\"iNMSOL\",\"description\":\"Aprenda Espa\u00f1ol con iNMSOL en Granada | Centro Acreditado por el Instituto Cervantes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#organization\",\"name\":\"Instituto Mediterr\u00e1neo Sol\",\"url\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inmsol.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-inmsol-1.png\",\"contentUrl\":\"https:\\\/\\\/www.inmsol.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-inmsol-1.png\",\"width\":136,\"height\":73,\"caption\":\"Instituto Mediterr\u00e1neo Sol\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/spanishcourses\",\"https:\\\/\\\/x.com\\\/StudyInGranada\",\"http:\\\/\\\/instagram.com\\\/imsolgranada\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/imsol-granada\",\"https:\\\/\\\/www.pinterest.es\\\/inmsol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChz-Qn_7coFMosY85iYMO4g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/#\\\/schema\\\/person\\\/18f18acd0397ef441e373e79ec3eb6ea\",\"name\":\"Javier Torres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90afa2d6499550218d247408758082af566e5ec3641e1b8eac0d7bb889344a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90afa2d6499550218d247408758082af566e5ec3641e1b8eac0d7bb889344a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90afa2d6499550218d247408758082af566e5ec3641e1b8eac0d7bb889344a55?s=96&d=mm&r=g\",\"caption\":\"Javier Torres\"},\"url\":\"https:\\\/\\\/www.inmsol.com\\\/es\\\/author\\\/javier\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocatoria D.E.L.E. 2013 | INMSOL","description":"FECHAS DE EX\u00c1MENES DELE 2013","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/","og_locale":"es_ES","og_type":"article","og_title":"Convocatoria D.E.L.E. 2013 | INMSOL","og_description":"FECHAS DE EX\u00c1MENES DELE 2013","og_url":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/","og_site_name":"iNMSOL","article_publisher":"https:\/\/www.facebook.com\/spanishcourses","article_published_time":"2010-02-19T09:06:34+00:00","article_modified_time":"2019-05-02T10:06:23+00:00","og_image":[{"width":320,"height":154,"url":"https:\/\/www.inmsol.com\/wp-content\/uploads\/2019\/08\/logo-inmsol.png","type":"image\/png"}],"author":"Javier Torres","twitter_misc":{"Escrito por":"Javier Torres"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/#article","isPartOf":{"@id":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/"},"author":{"name":"Javier Torres","@id":"https:\/\/www.inmsol.com\/es\/#\/schema\/person\/18f18acd0397ef441e373e79ec3eb6ea"},"headline":"Fechas de ex\u00e1menes D.E.L.E. 2013","datePublished":"2010-02-19T09:06:34+00:00","dateModified":"2019-05-02T10:06:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/"},"wordCount":96,"publisher":{"@id":"https:\/\/www.inmsol.com\/es\/#organization"},"articleSection":["Ex\u00e1menes y Certificaciones Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/","url":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/","name":"Convocatoria D.E.L.E. 2013 | INMSOL","isPartOf":{"@id":"https:\/\/www.inmsol.com\/es\/#website"},"datePublished":"2010-02-19T09:06:34+00:00","dateModified":"2019-05-02T10:06:23+00:00","description":"FECHAS DE EX\u00c1MENES DELE 2013","breadcrumb":{"@id":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inmsol.com\/es\/examenes-y-certificaciones-espanol\/fechas-de-examenes-dele-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accredited Center by Instituto Cervantes","item":"https:\/\/www.inmsol.com\/es\/pagina-ejemplo\/"},{"@type":"ListItem","position":2,"name":"Ex\u00e1menes y Certificaciones Espa\u00f1ol","item":"https:\/\/www.inmsol.com\/es\/category\/examenes-y-certificaciones-espanol\/"},{"@type":"ListItem","position":3,"name":"Fechas de ex\u00e1menes D.E.L.E. 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.inmsol.com\/es\/#website","url":"https:\/\/www.inmsol.com\/es\/","name":"iNMSOL","description":"Aprenda Espa\u00f1ol con iNMSOL en Granada | Centro Acreditado por el Instituto Cervantes","publisher":{"@id":"https:\/\/www.inmsol.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmsol.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.inmsol.com\/es\/#organization","name":"Instituto Mediterr\u00e1neo Sol","url":"https:\/\/www.inmsol.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.inmsol.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.inmsol.com\/wp-content\/uploads\/2023\/06\/logo-inmsol-1.png","contentUrl":"https:\/\/www.inmsol.com\/wp-content\/uploads\/2023\/06\/logo-inmsol-1.png","width":136,"height":73,"caption":"Instituto Mediterr\u00e1neo Sol"},"image":{"@id":"https:\/\/www.inmsol.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/spanishcourses","https:\/\/x.com\/StudyInGranada","http:\/\/instagram.com\/imsolgranada","https:\/\/es.linkedin.com\/company\/imsol-granada","https:\/\/www.pinterest.es\/inmsol\/","https:\/\/www.youtube.com\/channel\/UChz-Qn_7coFMosY85iYMO4g"]},{"@type":"Person","@id":"https:\/\/www.inmsol.com\/es\/#\/schema\/person\/18f18acd0397ef441e373e79ec3eb6ea","name":"Javier Torres","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/90afa2d6499550218d247408758082af566e5ec3641e1b8eac0d7bb889344a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90afa2d6499550218d247408758082af566e5ec3641e1b8eac0d7bb889344a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90afa2d6499550218d247408758082af566e5ec3641e1b8eac0d7bb889344a55?s=96&d=mm&r=g","caption":"Javier Torres"},"url":"https:\/\/www.inmsol.com\/es\/author\/javier\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/posts\/231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/comments?post=231"}],"version-history":[{"count":0,"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/posts\/231\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/media?parent=231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/categories?post=231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inmsol.com\/es\/wp-json\/wp\/v2\/tags?post=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}